{"id":1702,"date":"2023-12-16T13:00:20","date_gmt":"2023-12-16T11:00:20","guid":{"rendered":"http:\/\/www.madridlicencias.com\/blog\/?p=1702"},"modified":"2021-08-30T10:55:16","modified_gmt":"2021-08-30T08:55:16","slug":"licencia-apertura-actividad-gastrobar-espacio-artistico-cultural","status":"publish","type":"post","link":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/","title":{"rendered":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural"},"content":{"rendered":"<p style=\"text-align: justify;\">Hemos realizado el proyecto y tramitado la<a href=\"http:\/\/www.madridlicencias.com\"><strong> licencia de apertura y actividad<\/strong><\/a> de un espacio realmente muy especial. Este nuevo local est\u00e1 destinado a ser un <strong>Gastrobar, espacio Art\u00edsticio-Cultural y emocional<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1703\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg\" alt=\"Licencia funcionamiento gastrobar\" width=\"800\" height=\"534\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar-768x513.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Un lugar \u00fanico que no dejara de sorprenderte, tanto por la <strong>decoraci\u00f3n<\/strong> y el ambiente que se ha logrado como por la cantidad de <strong>eventos y experiencias<\/strong> que puedes disfrutar en \u00e9l.<\/p>\n<p style=\"text-align: justify;\">La <strong>tramitaci\u00f3n de la licencia de actividad y funcionamiento<\/strong> se ha realizado en este caso por el procedimiento de <a href=\"http:\/\/www.madridlicencias.com\/blog\/declaracion-responsable-dr-actividades-comerciales-servicios\/\"><strong>declaraci\u00f3n responsable<\/strong><\/a>. Dada la restrictiva normativa de la zona en cuanto a la apertura de nuevos espacios recreativos (bares, cafeter\u00edas, restaurantes, etc&#8230;) el espacio de <strong>Gastrobar<\/strong> se ha incluido como una <strong>actividad asociada<\/strong> al <strong>uso principal<\/strong> (<strong>galer\u00eda de arte<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Hay que recordar que tal y como marca el reglamento, cuando se implanta una <strong>actividad<\/strong> como uso asociado de otra, la asociada no podr\u00e1 superar en superficie m\u00e1s del <strong>25% de la superficie total<\/strong> del local y, por supuesto, deber\u00e1 contar con la dotaci\u00f3n obligatoria de aseos para personal y para p\u00fablico, estando estos \u00faltimos separados por sexos y existiendo al menos un aseo adaptado a minusv\u00e1lidos.<\/p>\n<p style=\"text-align: justify;\">Cuando se tramita <strong>licencias de actividad de restaurantes<\/strong>, bares o cualquier otra actividad en la que existan <strong>equipos reproducci\u00f3n sonora<\/strong> (hilo musical, televisi\u00f3n&#8230;) el local deber\u00e1 contar con un <strong>vest\u00edbulo ac\u00fastico<\/strong> y estar contar con un correcto aislamiento ac\u00fastico con el fin de no molestar a los vecinos de la zona.<\/p>\n<p style=\"text-align: justify;\">Como os comentaba al principio del art\u00edculo, no os pod\u00e9is perder ver este nuevo punto de encuentro: se llama \u00ab<strong>Espacio EO7<\/strong>\u00bb y est\u00e1 situado en la calle Francisco Ricci n\u00ba 7, 28 15, Madrid (Metro Arg\u00fcelles,\u00a0 y San Bernardo).<\/p>\n<p style=\"text-align: justify;\">En EO7 podr\u00e1s vivir <strong>experiencias emocionales<\/strong> en sus <span style=\"text-decoration: underline;\">charlas, talleres y cursos<\/span>. Ac\u00e9rcate a trav\u00e9s del <strong>arte, la danza, el teatro y la nutrici\u00f3n<\/strong> consciente hacia un profundo autoconocimiento personal, y distintas formas de expresi\u00f3n corporal y art\u00edstica.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1709\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencias-apertura-gastrobar.jpg\" alt=\"Licencias apertura gastrobar\" width=\"800\" height=\"534\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencias-apertura-gastrobar.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencias-apertura-gastrobar-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencias-apertura-gastrobar-768x513.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">En el local existen varias zonas diferenciadas por tem\u00e1ticas: zona GASTRO-ECOBAR , zona ARTE, zona TERAPIAS y zona FORMACION:<\/p>\n<p style=\"text-align: justify;\"><strong>ZONA GASTROBAR<\/strong><\/p>\n<p style=\"text-align: justify;\">La cuidada combinaci\u00f3n de <strong>alimentos de origen ecol\u00f3gico<\/strong> con especial ejecuci\u00f3n y presentaci\u00f3n, busca comunicar la excelencia del producto de una manera sencilla: infusiones, batidos, bocados de diferentes panes y platos para compartir. <strong>Coffee-break a los grupos que hagan actividades<\/strong>, y\u00a0 antes o despu\u00e9s de los <strong>eventos<\/strong> deseen pasar un rato compartiendo charla y <strong>una propuesta gastron\u00f3mica diferente<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1708\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-actividad-cafeter\u00eda.jpg\" alt=\"Licencia actividad cafeter\u00eda\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-actividad-cafeter\u00eda.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-actividad-cafeter\u00eda-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-actividad-cafeter\u00eda-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Lugar de encuentro<\/strong> entre la gastronom\u00eda y la nutrici\u00f3n, la alimentaci\u00f3n consciente inteligente y responsable, <strong>alimentaci\u00f3n cuidada y sana<\/strong> que ayuda en los procesos de sanaci\u00f3n a trav\u00e9s de men\u00fas, desayunos, superalimentos y licuados ecol\u00f3gicos.<\/p>\n<p style=\"text-align: justify;\"><strong>ZONA ARTE<\/strong><\/p>\n<p style=\"text-align: justify;\">Desde el espacio arte <strong>EO7\u00a0<\/strong> se busca <strong>comunicar a trav\u00e9s del arte<\/strong>, sentir, emocionar, cambiar la mirada de lo com\u00fan, ver por el \u201cojo del artista\u201d abrir el marco de conocimiento bajo la <strong>perspectiva enriquecedora y creativa de los artistas pl\u00e1sticos contempor\u00e1neos<\/strong>, observadores y transformadores de la realidad,\u00a0 que cuestionan lo establecido y aportan su mirada cr\u00edtica a lo cotidiano a trav\u00e9s de la libertad gestual, de la fusi\u00f3n de la cultura de la calle con la de las t\u00e9cnicas mas sofisticadas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1707\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-galer\u00eda-de-arte.jpg\" alt=\"Declaracion responsable galer\u00eda de arte\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-galer\u00eda-de-arte.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-galer\u00eda-de-arte-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-galer\u00eda-de-arte-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Eo7 incluye los <strong>trabajos de artistas con alto componente tecnol\u00f3gico<\/strong>, a trav\u00e9s de <strong>audiovisuales<\/strong>, tratamiento de\u00a0 <strong>im\u00e1genes electr\u00f3nicas<\/strong> y digitales, fotograf\u00eda, video-arte y video experimental,\u00a0 adentr\u00e1ndose en el significado de sus c\u00f3digos y profundizando en el propio metalenguaje que generan.<\/p>\n<p style=\"text-align: justify;\">Da cabida a una vivencia del <strong>arte m\u00e1s experiencial y transgresora<\/strong>, permiti\u00e9ndonos la b\u00fasqueda del goce sensorial como forma de acercamiento a la experiencia art\u00edstica, sin recurrir a par\u00e1metros racionales, partiendo de la variaci\u00f3n y el juego, y apelando a los referentes del espectador, su sensibilidad, su <strong>capacidad de asombro<\/strong>, de integraci\u00f3n y disfrute sensorial, dando prioridad a la inmersi\u00f3n en una experiencia est\u00e9tica.<\/p>\n<p style=\"text-align: justify;\"><strong>Espacio Arte EO7<\/strong>, busca la <strong>emoci\u00f3n<\/strong> del espectador, alej\u00e1ndose de las formas de expresi\u00f3n mas tradicionales, centradas en el objeto art\u00edstico, y desplazando el inter\u00e9s del soporte material a la experiencia comunitaria mas integradora e interactiva, generadora de reflexiones sobre el mundo en que vivimos.<\/p>\n<p style=\"text-align: justify;\"><strong>ZONA TERAPIAS<\/strong><\/p>\n<p style=\"text-align: justify;\">El espacio para la <strong>terapia hol\u00edstica<\/strong>, est\u00e1 dirigido por Jacinto Hermoso (psicoanalista, terapeuta humanista, formado en medicina china y psico-astrologia) .<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1704\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-terapias-alternativas.jpg\" alt=\"Declaracion responsable terapias alternativas\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-terapias-alternativas.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-terapias-alternativas-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-terapias-alternativas-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Incorpora din\u00e1mica Gestalt, t\u00e9cnicas sist\u00e9micas y de coach. Desde la <strong>psicolog\u00eda<\/strong> anal\u00edtica se trabaja\u00a0 sobre los bloqueos, los traumas, las din\u00e1micas emocionales, llegando a la <strong>resoluci\u00f3n de conflictos<\/strong>, tanto personales como de interrelaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Se indaga en buscar <strong>respuestas que desvelen las din\u00e1micas inconscientes<\/strong> generadoras de dolor para que a trav\u00e9s de su comprensi\u00f3n, sean un co-adyudante en los procesos de sanaci\u00f3n tanto emocionales como f\u00edsicos y espirituales.<\/p>\n<p style=\"text-align: justify;\">Como <strong>terapias complementarias<\/strong> cuentan con profesionales expertos en Medicina Natural, Ayurv\u00e9dica, homeopat\u00eda, nutrici\u00f3n celular, medicina tradicional China, Masaje terap\u00e9utico, Arteterapia, constelaciones familiares, Terapia Floral\u2026<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1706\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-terapias-alternativas.jpg\" alt=\"Licencia activiad terapias alternativas\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-terapias-alternativas.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-terapias-alternativas-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-terapias-alternativas-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Su intenci\u00f3n es que la din\u00e1mica de los terapeutas sea de evaluaci\u00f3n, diagn\u00f3stico y tratamiento, con el objetivo de coordinar las\u00a0 <strong>actividades f\u00edsicas<\/strong>,\u00a0 <strong>h\u00e1bitos nutricionales<\/strong> desde el\u00a0 gastro-bar y\u00a0 ofrecer a cada cliente la gu\u00eda mas eficaz para su tratamiento seg\u00fan el proceso en que se encuentre.<\/p>\n<p style=\"text-align: justify;\">As\u00ed pues a trav\u00e9s de la <strong>terapia emocional, f\u00edsica y nutricional<\/strong>, puedes ofrecer a sus clientes las mejores recomendaciones para mejorar su estado vital.<\/p>\n<p style=\"text-align: justify;\"><strong>ZONA FORMACION<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1705\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espect\u00e1culos.jpg\" alt=\"Licencia activiad espect\u00e1culos\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espect\u00e1culos.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espect\u00e1culos-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espect\u00e1culos-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Entre otras muchas cosas en este espacio tambi\u00e9n dan <strong>cursos muy especiales<\/strong>:<\/p>\n<p style=\"text-align: justify;\">Formaci\u00f3n terap\u00e9utica<br \/>\nCurso de astrolog\u00eda psicol\u00f3gica.<br \/>\nCurso de terapia floral -bach, california y korte.<br \/>\nCurso de tarot evolutivo y terap\u00e9utico.<br \/>\nCurso de diagn\u00f3stico y actuaci\u00f3n en terapias energ\u00e9ticas.<br \/>\nCurso masaje hol\u00edstico.<\/p>\n<p style=\"text-align: justify;\">Y otros <strong>muchos cursos de baile y movimiento<\/strong>!!!<\/p>\n<p style=\"text-align: justify;\"><strong>EO7 es un espacio ideal para la mente y el cuerpo<\/strong>, perfecto para tomar algo con los amigos, asistir a una presentaci\u00f3n de un libro, clases de danza y un largo etc\u00e9tera&#8230;. <strong>no te lo pierdas<\/strong>!!<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1710\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-cafeter\u00eda.jpg\" alt=\"Declaracion responsable cafeter\u00eda\" width=\"800\" height=\"534\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-cafeter\u00eda.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-cafeter\u00eda-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Declaracion-responsable-cafeter\u00eda-768x513.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p style=\"text-align: justify;\">Podr\u00e9is encontrar m\u00e1s informaci\u00f3n en: www.eo7.es<br \/>\nDirecci\u00f3n: calle Francisco Ricci n\u00ba 7, 28 15, Madrid<br \/>\nTel\u00e9fono y reservas: 91-138-50-06<br \/>\nEmail: hola@eo7.es<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1711\" src=\"http:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espacio-multifuncional.jpg\" alt=\"Licencia activiad espacio multifuncional\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espacio-multifuncional.jpg 800w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espacio-multifuncional-300x200.jpg 300w, https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-activiad-espacio-multifuncional-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1702&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;17&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (17 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural&quot;,&quot;width&quot;:&quot;138&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 138px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (17 votos)    <\/div>\n    <\/div>\n<p id=\"bte_opp\"><small><\/small><\/p>","protected":false},"excerpt":{"rendered":"<p>Hemos realizado el proyecto y tramitado la licencia de apertura y actividad de un espacio realmente muy especial. Este nuevo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_17708481_17708481":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[89],"tags":[448,449,31,450,446,445,47,447],"class_list":["post-1702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apertura","tag-academia","tag-baile","tag-bar","tag-danza","tag-ecobar","tag-gastrobar","tag-restaurante","tag-terapias-alternativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad\" \/>\n<meta property=\"og:description\" content=\"Hemos realizado el proyecto y tramitado la licencia de apertura y actividad de un espacio realmente muy especial. Este nuevo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/\" \/>\n<meta property=\"og:site_name\" content=\"Licencias de Apertura y Actividad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArquitectosVillanueva\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ArquitectosVillanueva\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-16T11:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gorka Villanueva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gorkavillanueva\" \/>\n<meta name=\"twitter:site\" content=\"@gorkavillanueva\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gorka Villanueva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/\"},\"author\":{\"name\":\"Gorka Villanueva\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#\\\/schema\\\/person\\\/33c4a38b2dfdf1309dd9a667d142c13c\"},\"headline\":\"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural\",\"datePublished\":\"2023-12-16T11:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/\"},\"wordCount\":1077,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#\\\/schema\\\/person\\\/33c4a38b2dfdf1309dd9a667d142c13c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/wp-content\\\/uploads\\\/Licencia-funcionamiento-gastrobar.jpg\",\"keywords\":[\"academia\",\"baile\",\"bar\",\"danza\",\"ecobar\",\"gastrobar\",\"restaurante\",\"terapias alternativas\"],\"articleSection\":[\"Apertura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/\",\"url\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/\",\"name\":\"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/wp-content\\\/uploads\\\/Licencia-funcionamiento-gastrobar.jpg\",\"datePublished\":\"2023-12-16T11:00:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/wp-content\\\/uploads\\\/Licencia-funcionamiento-gastrobar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/wp-content\\\/uploads\\\/Licencia-funcionamiento-gastrobar.jpg\",\"width\":800,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/\",\"name\":\"Licencias de Apertura y Actividad\",\"description\":\"Especializados en la tramitaci\u00f3n de licencias de actividad, licencias de apertura y declaraciones responsables. Resolvemos todas tus dudas sobre c\u00f3mo obtener tu licencia de funcionamiento y gestionar los tr\u00e1mites con el Ayuntamiento. Somos expertos en la gesti\u00f3n de aperturas de negocios. Este espacio est\u00e1 dise\u00f1ado para guiarte en el complejo mundo de las licencias de actividad y la burocracia urban\u00edstica. Aqu\u00ed encontrar\u00e1s an\u00e1lisis de normativa, gu\u00edas de procedimiento y ejemplos pr\u00e1cticos para tu negocio o local. Convierte tu proyecto en realidad con informaci\u00f3n t\u00e9cnica actualizada y fiable.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#\\\/schema\\\/person\\\/33c4a38b2dfdf1309dd9a667d142c13c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/#\\\/schema\\\/person\\\/33c4a38b2dfdf1309dd9a667d142c13c\",\"name\":\"Gorka Villanueva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g\",\"caption\":\"Gorka Villanueva\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.madridlicencias.com\",\"https:\\\/\\\/www.facebook.com\\\/ArquitectosVillanueva\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gorkavilla\\\/\"],\"url\":\"https:\\\/\\\/www.madridlicencias.com\\\/blog\\\/author\\\/madridli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/","og_locale":"es_ES","og_type":"article","og_title":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad","og_description":"Hemos realizado el proyecto y tramitado la licencia de apertura y actividad de un espacio realmente muy especial. Este nuevo [&hellip;]","og_url":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/","og_site_name":"Licencias de Apertura y Actividad","article_publisher":"https:\/\/www.facebook.com\/ArquitectosVillanueva","article_author":"https:\/\/www.facebook.com\/ArquitectosVillanueva","article_published_time":"2023-12-16T11:00:20+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg","type":"image\/jpeg"}],"author":"Gorka Villanueva","twitter_card":"summary_large_image","twitter_creator":"@gorkavillanueva","twitter_site":"@gorkavillanueva","twitter_misc":{"Escrito por":"Gorka Villanueva","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#article","isPartOf":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/"},"author":{"name":"Gorka Villanueva","@id":"https:\/\/www.madridlicencias.com\/blog\/#\/schema\/person\/33c4a38b2dfdf1309dd9a667d142c13c"},"headline":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural","datePublished":"2023-12-16T11:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/"},"wordCount":1077,"commentCount":0,"publisher":{"@id":"https:\/\/www.madridlicencias.com\/blog\/#\/schema\/person\/33c4a38b2dfdf1309dd9a667d142c13c"},"image":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg","keywords":["academia","baile","bar","danza","ecobar","gastrobar","restaurante","terapias alternativas"],"articleSection":["Apertura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/","url":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/","name":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural - Licencias de Apertura y Actividad","isPartOf":{"@id":"https:\/\/www.madridlicencias.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#primaryimage"},"image":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg","datePublished":"2023-12-16T11:00:20+00:00","breadcrumb":{"@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#primaryimage","url":"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg","contentUrl":"https:\/\/www.madridlicencias.com\/blog\/wp-content\/uploads\/Licencia-funcionamiento-gastrobar.jpg","width":800,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.madridlicencias.com\/blog\/licencia-apertura-actividad-gastrobar-espacio-artistico-cultural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.madridlicencias.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Licencia de Apertura y Actividad Gastrobar, espacio Art\u00edstico-Cultural"}]},{"@type":"WebSite","@id":"https:\/\/www.madridlicencias.com\/blog\/#website","url":"https:\/\/www.madridlicencias.com\/blog\/","name":"Licencias de Apertura y Actividad","description":"Especializados en la tramitaci\u00f3n de licencias de actividad, licencias de apertura y declaraciones responsables. Resolvemos todas tus dudas sobre c\u00f3mo obtener tu licencia de funcionamiento y gestionar los tr\u00e1mites con el Ayuntamiento. Somos expertos en la gesti\u00f3n de aperturas de negocios. Este espacio est\u00e1 dise\u00f1ado para guiarte en el complejo mundo de las licencias de actividad y la burocracia urban\u00edstica. Aqu\u00ed encontrar\u00e1s an\u00e1lisis de normativa, gu\u00edas de procedimiento y ejemplos pr\u00e1cticos para tu negocio o local. Convierte tu proyecto en realidad con informaci\u00f3n t\u00e9cnica actualizada y fiable.","publisher":{"@id":"https:\/\/www.madridlicencias.com\/blog\/#\/schema\/person\/33c4a38b2dfdf1309dd9a667d142c13c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.madridlicencias.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/www.madridlicencias.com\/blog\/#\/schema\/person\/33c4a38b2dfdf1309dd9a667d142c13c","name":"Gorka Villanueva","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g","caption":"Gorka Villanueva"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/2b22df0b555528a455bd6d7a4d62706746a36d31559440cca3a43072b34ff7ad?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.madridlicencias.com","https:\/\/www.facebook.com\/ArquitectosVillanueva","https:\/\/www.linkedin.com\/in\/gorkavilla\/"],"url":"https:\/\/www.madridlicencias.com\/blog\/author\/madridli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/posts\/1702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/comments?post=1702"}],"version-history":[{"count":3,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/posts\/1702\/revisions"}],"predecessor-version":[{"id":3554,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/posts\/1702\/revisions\/3554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/media\/1703"}],"wp:attachment":[{"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/media?parent=1702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/categories?post=1702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madridlicencias.com\/blog\/wp-json\/wp\/v2\/tags?post=1702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}